{"id":115,"date":"2022-01-18T17:27:51","date_gmt":"2022-01-18T17:27:51","guid":{"rendered":"https:\/\/www.thyroidaware.com\/br\/?p=115"},"modified":"2024-07-05T14:59:31","modified_gmt":"2024-07-05T17:59:31","slug":"disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe","status":"publish","type":"post","link":"https:\/\/www.thyroidaware.com\/br\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\/","title":{"rendered":"Dist\u00farbios n\u00e3o diagnosticados da tireoide podem afetar a fertilidade da m\u00e3e e a sa\u00fade do beb\u00ea"},"content":{"rendered":"\n<h4 class=\"wp-block-heading has-electviolet-color has-text-color\">Nesta Semana Internacional de Conscientiza\u00e7\u00e3o da Tireoide, queremos falar sobre como os problemas da tireoide podem afetar a m\u00e3e e o beb\u00ea. A campanha, desenvolvida pela Merck em estreita colabora\u00e7\u00e3o com a Federa\u00e7\u00e3o Internacional da Tireoide e a ThyroidChange, tem o objetivo de aumentar a conscientiza\u00e7\u00e3o sobre os dist\u00farbios da tireoide, abordando como a gl\u00e2ndula impacta na sa\u00fade antes, durante e ap\u00f3s a gravidez.<\/h4>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<div style=\"height:18px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Voc\u00ea sabia que dist\u00farbios da tireoide n\u00e3o diagnosticados podem afetar a fertilidade da m\u00e3e e a sa\u00fade do beb\u00ea?<\/strong><\/p>\n\n\n\n<p>Cerca de 1,6 bilh\u00e3o de pessoas ao redor do mundo podem estar sendo afetadas por dist\u00farbios na tireoide, sendo que 1 em cada 8 mulheres desenvolve algum problema com a gl\u00e2ndula durante a vida.<sup>1,2<\/sup> Ainda assim, existe uma surpreendente falta de conhecimento sobre o impacto que as condi\u00e7\u00f5es da tireoide podem ter na fertilidade.<\/p>\n\n\n\n<p>Uma pesquisa internacional, realizada pelo instituto YouGov*, mostrou a falta de conhecimento sobre o impacto que as condi\u00e7\u00f5es da tireoide podem ter na reprodu\u00e7\u00e3o, j\u00e1 que apenas um quarto (24%) dos entrevistados estava ciente de que os dist\u00farbios da gl\u00e2ndula n\u00e3o diagnosticados podem causar problemas de fertilidade. Al\u00e9m disso, as pessoas n\u00e3o sabem como as complica\u00e7\u00f5es da tireoide, sem investiga\u00e7\u00e3o pr\u00e9via, podem gerar dificuldades para m\u00e3e e beb\u00ea durante e ap\u00f3s a gravidez.<sup>3<\/sup><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>48%<\/strong> dos entrevistados achavam que era falso ou n\u00e3o sabiam que hipotireoidismo (tireoide hipoativa) poderia causar complica\u00e7\u00f5es para m\u00e3e e beb\u00ea durante a gravidez.<sup>3<\/sup><\/li>\n\n\n\n<li><strong>48%<\/strong> dos entrevistados t\u00eam consci\u00eancia de que \u00e9 crucial verificar os n\u00edveis de horm\u00f4nio tireoidiano para mulheres durante a gravidez.<sup>3<\/sup><\/li>\n\n\n\n<li><strong>26%<\/strong> dos entrevistados t\u00eam conhecimento que novas m\u00e3es, que nunca tiveram hist\u00f3rico anterior de doen\u00e7a da tireoide, podem desenvolver o dist\u00farbio denominado tireoidite p\u00f3s-parto (TPP), no primeiro ano ap\u00f3s o parto.<sup>3<\/sup><\/li>\n\n\n\n<li><strong>45%<\/strong> dos entrevistados estavam cientes de que rec\u00e9m-nascidos (com um m\u00eas ou menos de idade) precisam ser testados para hipotireoidismo cong\u00eanito (ou seja, tireoide hipoativa presente durante ou antes do nascimento), caso nas\u00e7am com a gl\u00e2ndula da tireoide ausente ou subdesenvolvida, o que pode exigir tratamento posterior.<sup>3<\/sup><\/li>\n<\/ul>\n\n\n\n<p>Resultados da pesquisa indicam que \u00e9 necess\u00e1rio educar melhor as pessoas sobre o impacto que os dist\u00farbios da tireoide sem diagn\u00f3stico podem causar na fertilidade e na sa\u00fade da m\u00e3e e do beb\u00ea.<sup>3<\/sup><\/p>\n\n\n\n<p><strong>Sobre os dist\u00farbios da tireoide<\/strong><\/p>\n\n\n\n<p>Quando n\u00e3o diagnosticados, os dist\u00farbios da tireoide podem afetar a fertilidade, o desenvolvimento fetal e a sa\u00fade da m\u00e3e e do beb\u00ea. No entanto, quando os dist\u00farbios da tireoide s\u00e3o diagnosticados e tratados adequadamente, os pacientes com dist\u00farbios da tireoide podem levar uma vida normal e ter uma gravidez saud\u00e1vel.<sup>4<\/sup><\/p>\n\n\n\n<p><strong>Dist\u00farbios da tireoide podem afetar a fertilidade.<\/strong><\/p>\n\n\n\n<p>Dist\u00farbios da tireoide, tanto o hipotireoidismo (tireoide hipoativa) quanto o hipertireoidismo (tireoide hiperativa), podem gerar problemas de fertilidade.<sup>4<\/sup> \u00c9 aconselh\u00e1vel visitar um(a) m\u00e9dico(a) se voc\u00ea:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Est\u00e1 tentando engravidar h\u00e1 pelo menos um ano;<sup>5<\/sup><\/li>\n\n\n\n<li>Tem o ciclo menstrual irregular;<sup>5<\/sup><\/li>\n\n\n\n<li>Teve mais de um aborto espont\u00e2neo;<sup>5<\/sup><\/li>\n\n\n\n<li>Tem hist\u00f3rico familiar de dist\u00farbios da tireoide;<sup>4<\/sup><\/li>\n\n\n\n<li>Tem endometriose ou s\u00edndrome dos ov\u00e1rios polic\u00edsticos (SOP).<sup>6<\/sup><\/li>\n<\/ul>\n\n\n\n<p><strong>A gravidez causa v\u00e1rias mudan\u00e7as hormonais e psicol\u00f3gicas que afetam a tireoide<\/strong><\/p>\n\n\n\n<p>\u00c9 crucial que a gl\u00e2ndula da tireoide funcione adequadamente durante a gravidez, uma vez que o feto depende de sua m\u00e3e para fornecer os horm\u00f4nios da tireoide, por meio da placenta, durante o primeiro trimestre.<sup>7<\/sup><\/p>\n\n\n\n<p>Os horm\u00f4nios da tireoide s\u00e3o essenciais para o desenvolvimento normal do c\u00e9rebro e do sistema nervoso do beb\u00ea, al\u00e9m de desempenharem um papel importante na manuten\u00e7\u00e3o da sa\u00fade da futura m\u00e3e.<sup>7<\/sup><\/p>\n\n\n\n<p>As gestantes devem ser testadas quanto aos n\u00edveis ideais de horm\u00f4nio tireoidiano durante a gravidez para verificar se o beb\u00ea est\u00e1 crescendo e se desenvolvendo normalmente.<\/p>\n\n\n\n<p><strong>Muitas m\u00e3es t\u00eam complica\u00e7\u00f5es na tireoide no primeiro ano ap\u00f3s o parto, mesmo que n\u00e3o tenham hist\u00f3rico anterior de dist\u00farbios da tireoide.<\/strong><\/p>\n\n\n\n<p>A condi\u00e7\u00e3o \u00e9 causada por tireoidite p\u00f3s-parto (PPT) \u00e9 uma condi\u00e7\u00e3o passageira e transit\u00f3ria. No entanto, para algumas mulheres, pode levar a uma tireoide hiperativa persistente (hipertireoidismo) ou evoluir para uma tireoide hipoativa (hipotireoidismo).<sup>4<\/sup><\/p>\n\n\n\n<p>Para qualquer d\u00favida, consulte um profissional de sa\u00fade.<\/p>\n\n\n\n<p><strong>Dist\u00farbios na tireoide tamb\u00e9m podem afetar os beb\u00eas.<\/strong><\/p>\n\n\n\n<p>Alguns rec\u00e9m-nascidos podem nascer sem a gl\u00e2ndula da tireoide ou com ela subdesenvolvida, dist\u00farbio conhecido como hipotireoidismo cong\u00eanito. Esses beb\u00eas n\u00e3o conseguem produzir horm\u00f4nios da tireoide suficientes para atender as necessidades do corpo, mas quando essa condi\u00e7\u00e3o \u00e9 diagnosticada precocemente \u00e9 poss\u00edvel control\u00e1-la.<sup>7<\/sup><\/p>\n\n\n\n<p><strong>Quais s\u00e3o os sintomas dos problemas na tireoide? Veja no nosso <a href=\"https:\/\/www.thyroidaware.com\/br\/symptom-checker\/\">Verificador de sintomas<\/a>**<\/strong><\/p>\n\n\n\n<p>Dar aten\u00e7\u00e3o aos sintomas \u00e9 importante para o diagn\u00f3stico, j\u00e1 que com o tratamento \u00e9 poss\u00edvel controlar os dist\u00farbios na tireoide.<sup>4 <\/sup>Se voc\u00ea est\u00e1 preocupado(a) com sintomas de um dist\u00farbio na tireoide, procure o aconselhamento de um profissional de sa\u00fade para que ele fa\u00e7a o exame de sangue e o diagn\u00f3stico correto.<\/p>\n\n\n\n<p>Voc\u00ea sabia? Al\u00e9m dos benef\u00edcios j\u00e1 conhecidos para a sa\u00fade em geral e qualidade de vida, o yoga pode ajudar pacientes com hipotireoidismo.<sup>8,9<\/sup> Que tal dar uma pequena pausa no dia para a sua sa\u00fade e fazer um exerc\u00edcio de yoga?<\/p>\n\n\n\n<p><strong>Como se envolver para promover a conscientiza\u00e7\u00e3o da falta de diagn\u00f3stico dos dist\u00farbios da tireoide na m\u00e3e e no beb\u00ea<\/strong><\/p>\n\n\n\n<p>Divulgue informa\u00e7\u00f5es com amigos e colegas sobre a import\u00e2ncia dos dist\u00farbios da tireoide na gravidez e vamos juntos fazer a diferen\u00e7a na vida de gestantes e pessoas que enfrentam essa doen\u00e7a. Acompanhe nossas postagens nas redes sociais (Facebook, Instagram e LinkedIn) e fa\u00e7a a sua parte compartilhando os conte\u00fados com seus amigos e familiares.<\/p>\n\n\n\n<p><strong>Por que estamos fazendo isso?<\/strong><\/p>\n\n\n\n<p>A Semana Internacional de Conscientiza\u00e7\u00e3o da Tireoide foi criada para conscientizar sobre o impacto que os dist\u00farbios da tireoide t\u00eam na qualidade de vida das pessoas quando n\u00e3o diagnosticados. Cerca de 1,6 bilh\u00e3o de pessoas ao redor do mundo podem estar sendo afetadas por dist\u00farbios na tireoide.<sup>1<\/sup> Uma vez diagnosticados, os dist\u00farbios da tireoide s\u00e3o trat\u00e1veis,<sup>4<\/sup> e a campanha tem o objetivo de aumentar a quantidade de testes e diagn\u00f3sticos em todo o mundo.<\/p>\n\n\n\n<p><em>*Esses dados resultam de uma pesquisa internacional da campanha da Semana Internacional de Consci\u00eancia da Tireoide, iniciada pela Merck e conduzida pela YouGov. O tamanho total da amostra foi de 7.208 adultos no Chile, Col\u00f4mbia, M\u00e9xico, Ar\u00e1bia Saudita, Indon\u00e9sia e China. O trabalho de campo foi realizado de 24 de mar\u00e7o a 6 de abril de 2020. A pesquisa foi realizada on-line. Os n\u00fameros foram ponderados e s\u00e3o representativos de todos os adultos (18 anos ou mais) em cada pa\u00eds.<\/em><\/p>\n\n\n\n<p><em>**O Verificador de sintomas n\u00e3o tem valor de diagn\u00f3stico, caso voc\u00ea identifique algum sintoma, visite um(a) m\u00e9dico(a).<\/em><a id=\"_msocom_1\"><\/a><\/p>\n\n\n      <section class=\"reference-content\">\n        <div class=\"ref-header\">\n          <a class=\"collapsed\" data-toggle=\"collapse\" href=\"#collapseExample\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">\n            <i class=\"fas\"><\/i>\n            Refer\u00eancias          <\/a>\n        <\/div>\n        <div class=\"collapse content-collapse\" id=\"collapseExample\">\n          <div class=\"row\">\n            <div class=\"col-12 text-reference\">\n              <ol>\n<li>Alam Khan, M. Muzaffar Ali Khan and Shamim Akhtar, 2002. Thyroid Disorders, Etiology and Prevalence. Journal of Medical Sciences, 2: 89-94.<\/li>\n<li>Thyroid awareness: what happens when this little gland goes haywire. Healthywomen. Dispon\u00edvel em: <a href=\"https:\/\/www.healthywomen.org\/content\/article\/thyroid-awareness-what-happens-when-little-gland-goes-haywire\">https:\/\/www.healthywomen.org\/content\/article\/thyroid-awareness-what-happens-when-little-gland-goes-haywire<\/a>. Acesso em maio de 2024.<\/li>\n<li>Pesquisa internacional \u2013 Campanha da Semana Internacional de Consci\u00eancia da Tireoide. Merck e YouGov, 2020.<\/li>\n<li>British Thyroid Foundation. Pregnancy and Fertility in Thyroid Disorders. Dispon\u00edvel em: <a href=\"https:\/\/www.btf-thyroid.org\/pregnancy-and-fertility-in-thyroid-disorders\">https:\/\/www.btf-thyroid.org\/pregnancy-and-fertility-in-thyroid-disorders<\/a>. Acesso em maio de 2024.<\/li>\n<li>Mayo Clinic. Infertility. Symptoms and causes. Dispon\u00edvel em: <a href=\"https:\/\/www.mayoclinic.org\/diseases-conditions\/infertility\/symptoms-causes\/syc-20354317\">https:\/\/www.mayoclinic.org\/diseases-conditions\/infertility\/symptoms-causes\/syc-20354317<\/a>. Acesso em maio de 2024.<\/li>\n<li>Poppe K, Velkeniers B, Glinoer D. Thyroid disease and female reproduction. Clin Endocrinol (Oxf). 2007 Mar;66(3):309-21.<\/li>\n<li>Thyroid UK. Better Thyroid Health: Congenital Hypothyroidism. Dispon\u00edvel em: <a href=\"https:\/\/thyroiduk.org\/if-you-are-hypothyroid\/about-hypothyroidism\/congenital-hypothyroidism\/\">https:\/\/thyroiduk.org\/if-you-are-hypothyroid\/about-hypothyroidism\/congenital-hypothyroidism\/<\/a>. Acesso em maio de 2024.<\/li>\n<li>Poonam Singh, Bhupinder Singh, Rachna Dave, Rakhi Udainiya. The impact of yoga upon female patients suffering from hypothyroidism. Complementary Therapies in Clinical Practice. Volume 17, Issue 3, 2011. Pages 132-134. ISSN 1744-3881.<\/li>\n<li>Javed Akhter. Role of yoga in improving quality of life of hypothyroidism patients. International Journal of Advances in MedicineAkhtarJ. Int JAdv Med. 2019 Apr;6(2):341-345.<\/li>\n<\/ol>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/section>\n\n\n\n<p>BR-EUT-00916\/Mayo-2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta Semana Internacional de Conscientiza\u00e7\u00e3o da Tireoide, queremos falar sobre como os problemas da tireoide podem afetar a m\u00e3e e o beb\u00ea&#8230;<\/p>\n","protected":false},"author":1,"featured_media":785,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[10],"tipo":[],"class_list":["post-115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias","tag-ultimas-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dist\u00farbios n\u00e3o diagnosticados da tireoide podem afetar a fertilidade da m\u00e3e e a sa\u00fade do beb\u00ea - Thyroid Br<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thyroidaware.com\/br\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dist\u00farbios n\u00e3o diagnosticados da tireoide podem afetar a fertilidade da m\u00e3e e a sa\u00fade do beb\u00ea - Thyroid Br\" \/>\n<meta property=\"og:description\" content=\"Nesta Semana Internacional de Conscientiza\u00e7\u00e3o da Tireoide, queremos falar sobre como os problemas da tireoide podem afetar a m\u00e3e e o beb\u00ea...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thyroidaware.com\/br\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\/\" \/>\n<meta property=\"og:site_name\" content=\"Thyroid Br\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-18T17:27:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-05T17:59:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.thyroidaware.com\/br\/wp-content\/uploads\/sites\/24\/2022\/01\/latest-news-nota-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.thyroidaware.com\\\/br\\\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thyroidaware.com\\\/br\\\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.thyroidaware.com\\\/br\\\/#\\\/schema\\\/person\\\/51c3c6636b958e23feaad469f4c594dc\"},\"headline\":\"Dist\u00farbios n\u00e3o diagnosticados da tireoide podem afetar a fertilidade da m\u00e3e e a sa\u00fade do beb\u00ea\",\"datePublished\":\"2022-01-18T17:27:51+00:00\",\"dateModified\":\"2024-07-05T17:59:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.thyroidaware.com\\\/br\\\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\\\/\"},\"wordCount\":1225,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.thyroidaware.com\\\/br\\\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thyroidaware.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2022\\\/01\\\/latest-news-nota-2.png\",\"keywords\":[\"\u00daltimas Not\u00edcias\"],\"articleSection\":[\"\u00daltimas Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.thyroidaware.com\\\/br\\\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.thyroidaware.com\\\/br\\\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\\\/\",\"url\":\"https:\\\/\\\/www.thyroidaware.com\\\/br\\\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\\\/\",\"name\":\"Dist\u00farbios n\u00e3o diagnosticados da tireoide podem afetar a fertilidade da m\u00e3e e a sa\u00fade do beb\u00ea - Thyroid Br\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thyroidaware.com\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.thyroidaware.com\\\/br\\\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thyroidaware.com\\\/br\\\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thyroidaware.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2022\\\/01\\\/latest-news-nota-2.png\",\"datePublished\":\"2022-01-18T17:27:51+00:00\",\"dateModified\":\"2024-07-05T17:59:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.thyroidaware.com\\\/br\\\/#\\\/schema\\\/person\\\/51c3c6636b958e23feaad469f4c594dc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.thyroidaware.com\\\/br\\\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.thyroidaware.com\\\/br\\\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.thyroidaware.com\\\/br\\\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.thyroidaware.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2022\\\/01\\\/latest-news-nota-2.png\",\"contentUrl\":\"https:\\\/\\\/www.thyroidaware.com\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2022\\\/01\\\/latest-news-nota-2.png\",\"width\":1440,\"height\":810},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.thyroidaware.com\\\/br\\\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.thyroidaware.com\\\/br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dist\u00farbios n\u00e3o diagnosticados da tireoide podem afetar a fertilidade da m\u00e3e e a sa\u00fade do beb\u00ea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.thyroidaware.com\\\/br\\\/#website\",\"url\":\"https:\\\/\\\/www.thyroidaware.com\\\/br\\\/\",\"name\":\"Thyroid Br\",\"description\":\"Otro sitio realizado con WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.thyroidaware.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.thyroidaware.com\\\/br\\\/#\\\/schema\\\/person\\\/51c3c6636b958e23feaad469f4c594dc\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e19618d25ff6b10df6f1b71737adc252b04237c83ec1e164f8fb3c98ec251260?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e19618d25ff6b10df6f1b71737adc252b04237c83ec1e164f8fb3c98ec251260?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e19618d25ff6b10df6f1b71737adc252b04237c83ec1e164f8fb3c98ec251260?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.thyroidaware.com\"],\"url\":\"https:\\\/\\\/www.thyroidaware.com\\\/br\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dist\u00farbios n\u00e3o diagnosticados da tireoide podem afetar a fertilidade da m\u00e3e e a sa\u00fade do beb\u00ea - Thyroid Br","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thyroidaware.com\/br\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\/","og_locale":"pt_BR","og_type":"article","og_title":"Dist\u00farbios n\u00e3o diagnosticados da tireoide podem afetar a fertilidade da m\u00e3e e a sa\u00fade do beb\u00ea - Thyroid Br","og_description":"Nesta Semana Internacional de Conscientiza\u00e7\u00e3o da Tireoide, queremos falar sobre como os problemas da tireoide podem afetar a m\u00e3e e o beb\u00ea...","og_url":"https:\/\/www.thyroidaware.com\/br\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\/","og_site_name":"Thyroid Br","article_published_time":"2022-01-18T17:27:51+00:00","article_modified_time":"2024-07-05T17:59:31+00:00","og_image":[{"width":1440,"height":810,"url":"https:\/\/www.thyroidaware.com\/br\/wp-content\/uploads\/sites\/24\/2022\/01\/latest-news-nota-2.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thyroidaware.com\/br\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\/#article","isPartOf":{"@id":"https:\/\/www.thyroidaware.com\/br\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\/"},"author":{"name":"admin","@id":"https:\/\/www.thyroidaware.com\/br\/#\/schema\/person\/51c3c6636b958e23feaad469f4c594dc"},"headline":"Dist\u00farbios n\u00e3o diagnosticados da tireoide podem afetar a fertilidade da m\u00e3e e a sa\u00fade do beb\u00ea","datePublished":"2022-01-18T17:27:51+00:00","dateModified":"2024-07-05T17:59:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thyroidaware.com\/br\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\/"},"wordCount":1225,"commentCount":0,"image":{"@id":"https:\/\/www.thyroidaware.com\/br\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.thyroidaware.com\/br\/wp-content\/uploads\/sites\/24\/2022\/01\/latest-news-nota-2.png","keywords":["\u00daltimas Not\u00edcias"],"articleSection":["\u00daltimas Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thyroidaware.com\/br\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thyroidaware.com\/br\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\/","url":"https:\/\/www.thyroidaware.com\/br\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\/","name":"Dist\u00farbios n\u00e3o diagnosticados da tireoide podem afetar a fertilidade da m\u00e3e e a sa\u00fade do beb\u00ea - Thyroid Br","isPartOf":{"@id":"https:\/\/www.thyroidaware.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thyroidaware.com\/br\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\/#primaryimage"},"image":{"@id":"https:\/\/www.thyroidaware.com\/br\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.thyroidaware.com\/br\/wp-content\/uploads\/sites\/24\/2022\/01\/latest-news-nota-2.png","datePublished":"2022-01-18T17:27:51+00:00","dateModified":"2024-07-05T17:59:31+00:00","author":{"@id":"https:\/\/www.thyroidaware.com\/br\/#\/schema\/person\/51c3c6636b958e23feaad469f4c594dc"},"breadcrumb":{"@id":"https:\/\/www.thyroidaware.com\/br\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thyroidaware.com\/br\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.thyroidaware.com\/br\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\/#primaryimage","url":"https:\/\/www.thyroidaware.com\/br\/wp-content\/uploads\/sites\/24\/2022\/01\/latest-news-nota-2.png","contentUrl":"https:\/\/www.thyroidaware.com\/br\/wp-content\/uploads\/sites\/24\/2022\/01\/latest-news-nota-2.png","width":1440,"height":810},{"@type":"BreadcrumbList","@id":"https:\/\/www.thyroidaware.com\/br\/disturbios-da-tireoide-nao-diagnosticados-podem-afetar-a-fertilidade-e-a-saude-da-mae-e-do-bebe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.thyroidaware.com\/br\/"},{"@type":"ListItem","position":2,"name":"Dist\u00farbios n\u00e3o diagnosticados da tireoide podem afetar a fertilidade da m\u00e3e e a sa\u00fade do beb\u00ea"}]},{"@type":"WebSite","@id":"https:\/\/www.thyroidaware.com\/br\/#website","url":"https:\/\/www.thyroidaware.com\/br\/","name":"Thyroid Br","description":"Otro sitio realizado con WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thyroidaware.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.thyroidaware.com\/br\/#\/schema\/person\/51c3c6636b958e23feaad469f4c594dc","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e19618d25ff6b10df6f1b71737adc252b04237c83ec1e164f8fb3c98ec251260?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e19618d25ff6b10df6f1b71737adc252b04237c83ec1e164f8fb3c98ec251260?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e19618d25ff6b10df6f1b71737adc252b04237c83ec1e164f8fb3c98ec251260?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.thyroidaware.com"],"url":"https:\/\/www.thyroidaware.com\/br\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.thyroidaware.com\/br\/wp-json\/wp\/v2\/posts\/115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thyroidaware.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thyroidaware.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thyroidaware.com\/br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thyroidaware.com\/br\/wp-json\/wp\/v2\/comments?post=115"}],"version-history":[{"count":23,"href":"https:\/\/www.thyroidaware.com\/br\/wp-json\/wp\/v2\/posts\/115\/revisions"}],"predecessor-version":[{"id":1037,"href":"https:\/\/www.thyroidaware.com\/br\/wp-json\/wp\/v2\/posts\/115\/revisions\/1037"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thyroidaware.com\/br\/wp-json\/wp\/v2\/media\/785"}],"wp:attachment":[{"href":"https:\/\/www.thyroidaware.com\/br\/wp-json\/wp\/v2\/media?parent=115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thyroidaware.com\/br\/wp-json\/wp\/v2\/categories?post=115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thyroidaware.com\/br\/wp-json\/wp\/v2\/tags?post=115"},{"taxonomy":"tipo","embeddable":true,"href":"https:\/\/www.thyroidaware.com\/br\/wp-json\/wp\/v2\/tipo?post=115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}